{"id":141,"name":"Equipo Digital Home de Telef\u00f3nica","url":"https:\/\/www.telefonica.com\/es\/","description":"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.","link":"https:\/\/www.movistar.es\/blog\/author\/digitalhome\/","slug":"digitalhome","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7","48":"https:\/\/secure.gravatar.com\/avatar\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7","96":"https:\/\/secure.gravatar.com\/avatar\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7"},"meta":{"jetpack_donation_warning_dismissed":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Equipo Digital Home de Telef\u00f3nica<\/title>\n<meta name=\"description\" content=\"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Equipo Digital Home de Telef\u00f3nica\" \/>\n<meta property=\"og:description\" content=\"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.movistar.es\/blog\/author\/digitalhome\/\" \/>\n<meta property=\"og:site_name\" content=\"Movistar blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/8ca61f64e6b95b1ebb2cce3c35ff9f50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/author\\\/digitalhome\\\/\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/author\\\/digitalhome\\\/\",\"name\":\"Equipo Digital Home de Telef\u00f3nica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#website\"},\"description\":\"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/author\\\/digitalhome\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.movistar.es\\\/blog\\\/author\\\/digitalhome\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/author\\\/digitalhome\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Equipo Digital Home de Telef\u00f3nica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/\",\"name\":\"Movistar blog\",\"description\":\"Movistar Blog. Informaci\u00f3n y m\u00e1s sobre los productos y servicios de Movistar\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#organization\",\"name\":\"Movistar blog\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/logo_movistar-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/logo_movistar-1.svg\",\"width\":369,\"height\":272,\"caption\":\"Movistar blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#\\\/schema\\\/person\\\/017db1b90e8802ac5dfd3618d922a394\",\"name\":\"Equipo Digital Home de Telef\u00f3nica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7e6431db462646a778ad8d8ec435ad57e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7\",\"caption\":\"Equipo Digital Home de Telef\u00f3nica\"},\"description\":\"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.\",\"sameAs\":[\"https:\\\/\\\/www.telefonica.com\\\/es\\\/\",\"telefonica\",\"https:\\\/\\\/www.instagram.com\\\/telefonica\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/telefonica\",\"https:\\\/\\\/x.com\\\/telefonica\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7LZo_P6m0W7SDDA8h3CLvg\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Telefnica\"],\"knowsAbout\":[\"innovaci\u00f3n\",\"tecnolog\u00eda\",\"hogar digital\",\"hogar inteligente\"],\"worksFor\":\"Telef\u00f3nica\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/author\\\/digitalhome\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Equipo Digital Home de Telef\u00f3nica","description":"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"profile","og_title":"Equipo Digital Home de Telef\u00f3nica","og_description":"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.","og_url":"https:\/\/www.movistar.es\/blog\/author\/digitalhome\/","og_site_name":"Movistar blog","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/8ca61f64e6b95b1ebb2cce3c35ff9f50","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.movistar.es\/blog\/author\/digitalhome\/","url":"https:\/\/www.movistar.es\/blog\/author\/digitalhome\/","name":"Equipo Digital Home de Telef\u00f3nica","isPartOf":{"@id":"https:\/\/www.movistar.es\/blog\/#website"},"description":"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.","breadcrumb":{"@id":"https:\/\/www.movistar.es\/blog\/author\/digitalhome\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.movistar.es\/blog\/author\/digitalhome\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.movistar.es\/blog\/author\/digitalhome\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.movistar.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Archives for Equipo Digital Home de Telef\u00f3nica"}]},{"@type":"WebSite","@id":"https:\/\/www.movistar.es\/blog\/#website","url":"https:\/\/www.movistar.es\/blog\/","name":"Movistar blog","description":"Movistar Blog. Informaci\u00f3n y m\u00e1s sobre los productos y servicios de Movistar","publisher":{"@id":"https:\/\/www.movistar.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.movistar.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.movistar.es\/blog\/#organization","name":"Movistar blog","url":"https:\/\/www.movistar.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.movistar.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/05\/logo_movistar-1.svg","contentUrl":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/05\/logo_movistar-1.svg","width":369,"height":272,"caption":"Movistar blog"},"image":{"@id":"https:\/\/www.movistar.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.movistar.es\/blog\/#\/schema\/person\/017db1b90e8802ac5dfd3618d922a394","name":"Equipo Digital Home de Telef\u00f3nica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7e6431db462646a778ad8d8ec435ad57e","url":"https:\/\/secure.gravatar.com\/avatar\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd5d081bad86885415e3c00f9694e72a561b53c12628d54d9a8b054807e947a7","caption":"Equipo Digital Home de Telef\u00f3nica"},"description":"En el equipo de Hogar Digital de Telef\u00f3nica somos expertos en conectividad, tecnolog\u00eda e innovaci\u00f3n. Dise\u00f1amos productos y dispositivos inteligentes pensados para el hogar. En este blog te contamos las caracter\u00edsticas y como sacar partido a tu hogar conectado. Desde un asistente de voz (AURA) hasta living apps para disfrutar en Movistar Plus+.","sameAs":["https:\/\/www.telefonica.com\/es\/","telefonica","https:\/\/www.instagram.com\/telefonica","https:\/\/www.linkedin.com\/company\/telefonica","https:\/\/x.com\/telefonica","https:\/\/www.youtube.com\/channel\/UC7LZo_P6m0W7SDDA8h3CLvg","https:\/\/es.wikipedia.org\/wiki\/Telefnica"],"knowsAbout":["innovaci\u00f3n","tecnolog\u00eda","hogar digital","hogar inteligente"],"worksFor":"Telef\u00f3nica","mainEntityOfPage":{"@id":"https:\/\/www.movistar.es\/blog\/author\/digitalhome\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/users\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/users"}]}}