{"id":2619,"date":"2021-02-09T11:00:00","date_gmt":"2021-02-09T10:00:00","guid":{"rendered":"https:\/\/www.movistar.es\/blog\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/"},"modified":"2022-05-04T20:53:08","modified_gmt":"2022-05-04T18:53:08","slug":"receta-medica-online-como-funciona-su-reglamentacion-en-espana","status":"publish","type":"post","link":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/","title":{"rendered":"Receta m\u00e9dica online: Espa\u00f1a a la vanguardia de la telemedicina en Europa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>La receta m\u00e9dica online<\/em> es un ejemplo de c\u00f3mo <strong>el uso de Internet y los medios digitales han mejorado la prestaci\u00f3n de servicios de la salud.<\/strong> La <a rel=\"noreferrer noopener\" href=\"https:\/\/blogthinkbig.com\/telemedicina\" data-type=\"URL\" data-id=\"https:\/\/blogthinkbig.com\/telemedicina\" target=\"_blank\">telemedicina<\/a>, por su parte, es una tendencia que se ha potenciado con la <em>pandemia de la COVID-19<\/em>, con un crecimiento importante en Espa\u00f1a. Una tendencia en la que Telef\u00f3nica ya est\u00e1 trabajando con su servicio de <a rel=\"noreferrer noopener\" href=\"https:\/\/www.movistar.es\/particulares\/telemedicina-medico-online\/\" target=\"_blank\">Movistar Salud<\/a> y del que puedes tener m\u00e1s informaci\u00f3n a trav\u00e9s de la <a href=\"https:\/\/blogthinkbig.com\/living-app-movistar-salud\" target=\"_blank\" rel=\"noreferrer noopener\">Living App Movistar Salud.<\/a> <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"receta-medica-online-una-solucion-en-tiempos-de-contingencia\">Receta m\u00e9dica online: una soluci\u00f3n en tiempos de contingencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El uso de la <em>receta m\u00e9dica online<\/em> ha tenido un <strong>crecimiento sostenido en los \u00faltimos a\u00f1os.<\/strong> Lo anterior se debe, en buena parte, a que <em>muchas farmacias han transformado digitalmente sus procesos de promoci\u00f3n y venta.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro incentivo para su uso es que el servicio del Sistema Nacional de Salud (RESNS) es interoperable entre comunidades aut\u00f3nomas. Esto permite la <strong>dispensaci\u00f3n de la medicaci\u00f3n prescrita con solo presentar la tarjeta sanitaria individual en las farmacias.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cambio en la actitud del cliente tambi\u00e9n es un incentivo para su uso. Las personas se suman por comodidad o por necesidad al uso de los servicios de <a href=\"https:\/\/empresas.blogthinkbig.com\/ehealth-o-esalud\/\" data-type=\"URL\" data-id=\"https:\/\/empresas.blogthinkbig.com\/ehealth-o-esalud\/\" target=\"_blank\" rel=\"noreferrer noopener\">e-salud<\/a>. Adem\u00e1s, <strong>la contingencia y el confinamiento por el COVID-19 han limitado la movilidad de las personas.<\/strong> Estas limitaciones han motivado en Espa\u00f1a el incremento en la demanda de las consultas m\u00e9dicas online.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"regulacion-en-espana-de-la-receta-medica-online\">Regulaci\u00f3n en Espa\u00f1a de la receta m\u00e9dica online<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al contar con consultas m\u00e9dicas online tambi\u00e9n se hace necesario que las recetas m\u00e9dicas se gestionen por medios digitales. Sin embargo,<em> la ley en Espa\u00f1a proh\u00edbe la venta a distancia de medicamentos y productos sanitarios sujetos a prescripci\u00f3n<\/em> o receta m\u00e9dica. Esto incluye las ventas por correspondencia o medios telem\u00e1ticos. <strong>La dispensaci\u00f3n de <em>receta m\u00e9dica online<\/em> solo la pueden hacer profesionales farmac\u00e9uticos, m\u00e9dicos, odont\u00f3logos o pod\u00f3logos,<\/strong> legalmente facultados para ello. De acuerdo con Asefarma (2019), toda receta m\u00e9dica online debe llegar a las farmacias debidamente elaborada e incluyendo:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Datos del prescriptor.<\/li><li>Datos en la prescripci\u00f3n.<\/li><li>Fechas de prescripci\u00f3n o, en su defecto, de dispensaci\u00f3n.<\/li><li>Datos del paciente.<\/li><li>Autovisado del prescriptor y visado de inspecci\u00f3n en los casos donde aplica.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, para controlar la emisi\u00f3n de la receta m\u00e9dica online, as\u00ed como la venta de medicamentos recetados, se ha creado un marco de regulaci\u00f3n legislativa que se ha ido actualizando con los a\u00f1os.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"regimen-juridico-administrativo-de-la-receta-medica-online\">R\u00e9gimen jur\u00eddico-administrativo de la receta m\u00e9dica online<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En Espa\u00f1a hay un marco de ley amplio asociado a la autorizaci\u00f3n, control, prescripci\u00f3n y venta de medicamentos. Adicionalmente, se han desarrollado varias plataformas para implementar los sistemas de receta m\u00e9dica online. A continuaci\u00f3n indicamos la <strong>normativa inicial y las actualizaciones m\u00e1s recientes que aplican a la <em>receta m\u00e9dica online:<\/em><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Directiva 2001\/83\/CE, estableciendo un c\u00f3digo comunitario sobre medicamentos para uso humano.<\/li><li>Ley 62\/2003, 30 de diciembre, asociada al inicio y aparici\u00f3n de la receta m\u00e9dica online en Espa\u00f1a.<\/li><li>Ley 29\/2006, 26 de julio, de garant\u00edas y uso racional de los medicamentos y productos sanitarios (LGURMPS). Texto refundido de 2015 (TRLGURMPS).<\/li><li>Real Decreto 870\/2013, 08 de noviembre, que regula la venta a distancia o telem\u00e1tica de medicamentos de uso humano no sujetos a prescripci\u00f3n m\u00e9dica.<\/li><li>Ley Org\u00e1nica 3\/2018, 05 de diciembre, de protecci\u00f3n de datos y garant\u00eda de los derechos digitales.<\/li><li>Sistema de Receta M\u00e9dica Online con firma digital, 2015, creado como plataforma para regular la venta de f\u00e1rmacos en Internet.<\/li><li>Sistemas de autorizaci\u00f3n de la Agencia Espa\u00f1ola de Medicamentos y Productos Sanitarios (<em>AEMPS<\/em>).<\/li><li>Sitio web <em>Distafarma<\/em>, mapa y listado de farmacias que realizan la venta a distancia.<\/li><li>Sistema de \u201c<em>eReceta Privada Contingencia COVID-19<\/em>\u201d, puesto en marcha en 2020.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/blogthinkbig.com\/wp-content\/uploads\/sites\/4\/2021\/01\/right-4926156_640.jpg?resize=610,407\" alt=\"Receta m\u00e9dica online\" class=\"wp-image-193075\" \/><figcaption><em>Jur\u00eddico-administrativo:<\/em>&nbsp;Foto v\u00eda&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/pixabay.com\/es\/users\/herbinisaac-3467892\/\" data-type=\"URL\" data-id=\"https:\/\/pixabay.com\/es\/users\/herbinisaac-3467892\/\" target=\"_blank\">Herbinisaac<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"espana-desarrolla-el-sistema-de-ereceta-privada-contingencia-covid-19\">Espa\u00f1a desarrolla el sistema de \u201ceReceta Privada Contingencia COVID-19\u201d<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El sistema de Receta Electr\u00f3nica Privada <em>se desarrolla en Espa\u00f1a al amparo del art\u00edculo 14.4 del Real Decreto 1718\/2010, 17 de diciembre.<\/em> Finalmente, este se hace realidad en diciembre de 2019. Seg\u00fan Gaceta Dental (2019), el desarrollo de este sistema <strong>busca garantizar la seguridad de los datos del paciente y evitar el intrusismo profesional.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, la plataforma evolucion\u00f3 al sistema de \u201c<em>eReceta Privada Contingencia COVID-19<\/em>\u201d. Para llegar a su lanzamiento, se tuvieron que superar etapas con pruebas de integraci\u00f3n t\u00e9cnica, homologaci\u00f3n, interoperabilidad y correcto funcionamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a esto, el listado de entidades privadas acreditadas que pueden emitir una <em>receta m\u00e9dica online<\/em> ha incrementado. Como resultado, cada vez hay m\u00e1s centros de salud y aseguradoras privadas que ofrecen sus plataformas a profesionales prescriptores de medicamentos. Algunos de <strong>sus beneficios son:<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"beneficios-del-sistema-de-receta-electronica-privada\">Beneficios del sistema de Receta Electr\u00f3nica Privada<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Define mecanismos t\u00e9cnicos m\u00ednimos comunes y procedimientos de homologaci\u00f3n para garantizar la interoperabilidad.<\/li><li>Apoyo al paciente para que pueda obtener tratamiento prescrito en forma electr\u00f3nica desde plataformas acreditadas.<\/li><li>Intercambio de informaci\u00f3n (datos, <a href=\"https:\/\/blogthinkbig.com\/historial-medico-electronico\" data-type=\"URL\" data-id=\"https:\/\/blogthinkbig.com\/historial-medico-electronico\" target=\"_blank\" rel=\"noreferrer noopener\">historial m\u00e9dico electr\u00f3nico<\/a>) en condiciones de seguridad y confidencialidad.<\/li><li>Prescripci\u00f3n de la<em> receta m\u00e9dica online <\/em>por parte de cualquier profesional sanitario habilitado para tal fin.<\/li><li>Define los requisitos para la certificaci\u00f3n de sistemas de prescripci\u00f3n y repositorios de prescripciones.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los avances en la implementaci\u00f3n y uso de la<em> <strong>receta m\u00e9dica online<\/strong><\/em> se han fundamentado en la evoluci\u00f3n de la legislaci\u00f3n m\u00e9dica y los acuerdos comunitarios. El avance en el <em>e-health<\/em> y la respuesta a coyunturas como la pandemia COVID-19 tambi\u00e9n han incrementado su uso. Espa\u00f1a es un ejemplo exitoso en la implantaci\u00f3n de la receta electr\u00f3nica p\u00fablica y privada.<strong> De la tradicional receta en papel ha pasado a la receta m\u00e9dica online con una red que conecta en tiempo real al menos a 22.000 farmacias<\/strong>. Sin duda alguna, Espa\u00f1a es un <a href=\"https:\/\/www.telefonica.com\/es\/web\/sala-de-prensa\/-\/movistar-y-teladoc-lanzan-movistar-salud-un-pionero-servicio-de-telemedicina-y-bienestar-remoto-para-particulares-y-empresas\" target=\"_blank\" rel=\"noreferrer noopener\">pa\u00eds a la vanguardia<\/a> en el desarrollo de servicios digitales de telemedicina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Im\u00e1gen de cabecera:<\/em>&nbsp;<a href=\"https:\/\/unsplash.com\/@franciscovenancio\" data-type=\"URL\" data-id=\"https:\/\/unsplash.com\/@franciscovenancio\" target=\"_blank\" rel=\"noreferrer noopener\">Francisco Ven\u00e2ncio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La receta m\u00e9dica online es un ejemplo de c\u00f3mo el uso de Internet y los medios digitales han mejorado la prestaci\u00f3n de servicios de la salud. La telemedicina, por su parte, es una tendencia que [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"area":[],"cluster":[99],"linea_editorial":[9],"coauthors":[],"class_list":["post-2619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","cluster-salud","linea_editorial-movistar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Receta m\u00e9dica online: beneficios, regulaci\u00f3n y novedades en Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"La receta m\u00e9dica online es un exitoso ejemplo del avance que tiene la telemedicina, al dispensar por medios electr\u00f3nicos la medicaci\u00f3n del paciente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Receta m\u00e9dica online: Espa\u00f1a a la vanguardia de la telemedicina en Europa\" \/>\n<meta property=\"og:description\" content=\"La receta m\u00e9dica online es un exitoso ejemplo del avance que tiene la telemedicina, al dispensar por medios electr\u00f3nicos la medicaci\u00f3n del paciente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Movistar blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-09T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-04T18:53:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/04\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moncho Terol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moncho Terol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/\"},\"author\":{\"name\":\"Moncho Terol\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#\\\/schema\\\/person\\\/6709434912eb0daaaddee544cf38a9ae\"},\"headline\":\"Receta m\u00e9dica online: Espa\u00f1a a la vanguardia de la telemedicina en Europa\",\"datePublished\":\"2021-02-09T10:00:00+00:00\",\"dateModified\":\"2022-05-04T18:53:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/\"},\"wordCount\":1029,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/\",\"name\":\"Receta m\u00e9dica online: beneficios, regulaci\u00f3n y novedades en Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg\",\"datePublished\":\"2021-02-09T10:00:00+00:00\",\"dateModified\":\"2022-05-04T18:53:08+00:00\",\"description\":\"La receta m\u00e9dica online es un exitoso ejemplo del avance que tiene la telemedicina, al dispensar por medios electr\u00f3nicos la medicaci\u00f3n del paciente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg\",\"contentUrl\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg\",\"width\":1800,\"height\":665},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/salud\\\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Receta m\u00e9dica online: Espa\u00f1a a la vanguardia de la telemedicina en Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/\",\"name\":\"Movistar blog\",\"description\":\"Movistar Blog. Informaci\u00f3n y m\u00e1s sobre los productos y servicios de Movistar\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#organization\",\"name\":\"Movistar blog\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/logo_movistar-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/logo_movistar-1.svg\",\"width\":369,\"height\":272,\"caption\":\"Movistar blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/#\\\/schema\\\/person\\\/6709434912eb0daaaddee544cf38a9ae\",\"name\":\"Moncho Terol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/657d2881666fa6ff6ec0626d654e2371b6c96dba39c3cba27d62cb7467aceb02776a94a272c4bed6827bd6063bc4c464\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/657d2881666fa6ff6ec0626d654e2371b6c96dba39c3cba27d62cb7467aceb02\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/657d2881666fa6ff6ec0626d654e2371b6c96dba39c3cba27d62cb7467aceb02\",\"caption\":\"Moncho Terol\"},\"description\":\"El futuro lo escribimos todos juntos. Me gustan las redes y la conectividad.\",\"url\":\"https:\\\/\\\/www.movistar.es\\\/blog\\\/author\\\/monchoterol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Receta m\u00e9dica online: beneficios, regulaci\u00f3n y novedades en Espa\u00f1a","description":"La receta m\u00e9dica online es un exitoso ejemplo del avance que tiene la telemedicina, al dispensar por medios electr\u00f3nicos la medicaci\u00f3n del paciente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/","og_locale":"es_ES","og_type":"article","og_title":"Receta m\u00e9dica online: Espa\u00f1a a la vanguardia de la telemedicina en Europa","og_description":"La receta m\u00e9dica online es un exitoso ejemplo del avance que tiene la telemedicina, al dispensar por medios electr\u00f3nicos la medicaci\u00f3n del paciente.","og_url":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/","og_site_name":"Movistar blog","article_published_time":"2021-02-09T10:00:00+00:00","article_modified_time":"2022-05-04T18:53:08+00:00","og_image":[{"width":1800,"height":665,"url":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/04\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg","type":"image\/jpeg"}],"author":"Moncho Terol","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Moncho Terol","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/#article","isPartOf":{"@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/"},"author":{"name":"Moncho Terol","@id":"https:\/\/www.movistar.es\/blog\/#\/schema\/person\/6709434912eb0daaaddee544cf38a9ae"},"headline":"Receta m\u00e9dica online: Espa\u00f1a a la vanguardia de la telemedicina en Europa","datePublished":"2021-02-09T10:00:00+00:00","dateModified":"2022-05-04T18:53:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/"},"wordCount":1029,"commentCount":0,"publisher":{"@id":"https:\/\/www.movistar.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/04\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/","url":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/","name":"Receta m\u00e9dica online: beneficios, regulaci\u00f3n y novedades en Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.movistar.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/04\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg","datePublished":"2021-02-09T10:00:00+00:00","dateModified":"2022-05-04T18:53:08+00:00","description":"La receta m\u00e9dica online es un exitoso ejemplo del avance que tiene la telemedicina, al dispensar por medios electr\u00f3nicos la medicaci\u00f3n del paciente.","breadcrumb":{"@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/#primaryimage","url":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/04\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg","contentUrl":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/04\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg","width":1800,"height":665},{"@type":"BreadcrumbList","@id":"https:\/\/www.movistar.es\/blog\/salud\/receta-medica-online-como-funciona-su-reglamentacion-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.movistar.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Receta m\u00e9dica online: Espa\u00f1a a la vanguardia de la telemedicina en Europa"}]},{"@type":"WebSite","@id":"https:\/\/www.movistar.es\/blog\/#website","url":"https:\/\/www.movistar.es\/blog\/","name":"Movistar blog","description":"Movistar Blog. Informaci\u00f3n y m\u00e1s sobre los productos y servicios de Movistar","publisher":{"@id":"https:\/\/www.movistar.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.movistar.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.movistar.es\/blog\/#organization","name":"Movistar blog","url":"https:\/\/www.movistar.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.movistar.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/05\/logo_movistar-1.svg","contentUrl":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/05\/logo_movistar-1.svg","width":369,"height":272,"caption":"Movistar blog"},"image":{"@id":"https:\/\/www.movistar.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.movistar.es\/blog\/#\/schema\/person\/6709434912eb0daaaddee544cf38a9ae","name":"Moncho Terol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/657d2881666fa6ff6ec0626d654e2371b6c96dba39c3cba27d62cb7467aceb02776a94a272c4bed6827bd6063bc4c464","url":"https:\/\/secure.gravatar.com\/avatar\/657d2881666fa6ff6ec0626d654e2371b6c96dba39c3cba27d62cb7467aceb02","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/657d2881666fa6ff6ec0626d654e2371b6c96dba39c3cba27d62cb7467aceb02","caption":"Moncho Terol"},"description":"El futuro lo escribimos todos juntos. Me gustan las redes y la conectividad.","url":"https:\/\/www.movistar.es\/blog\/author\/monchoterol\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.movistar.es\/blog\/wp-content\/uploads\/sites\/3\/2022\/04\/Infraestructuras-Tecnologicas-de-la-Salud-datos-medicos-en-riesgo-ciberseguridad.jpg","_links":{"self":[{"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/posts\/2619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/comments?post=2619"}],"version-history":[{"count":2,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/posts\/2619\/revisions"}],"predecessor-version":[{"id":11539,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/posts\/2619\/revisions\/11539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/media\/249"}],"wp:attachment":[{"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/media?parent=2619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/categories?post=2619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/tags?post=2619"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/area?post=2619"},{"taxonomy":"cluster","embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/cluster?post=2619"},{"taxonomy":"linea_editorial","embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/linea_editorial?post=2619"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.movistar.es\/blog\/wp-json\/wp\/v2\/coauthors?post=2619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}